{"id":334309,"date":"2023-08-08T14:05:20","date_gmt":"2023-08-08T21:05:20","guid":{"rendered":"https:\/\/bookafy.com\/?page_id=334309"},"modified":"2026-07-12T00:16:30","modified_gmt":"2026-07-12T07:16:30","slug":"automate-the-process","status":"publish","type":"page","link":"https:\/\/bookafy.com\/pl\/automate-the-process\/","title":{"rendered":"Automate the process"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"334309\" class=\"elementor elementor-334309\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61557d2c elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"61557d2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1df35644\" data-id=\"1df35644\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cd0f87 elementor-widget__width-auto elementor-absolute elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"2cd0f87\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"464\" height=\"113\" src=\"https:\/\/bookafy.com\/wp-content\/uploads\/2023\/02\/bookafy-logo-blue.png\" class=\"attachment-full size-full wp-image-308848\" alt=\"|\" srcset=\"https:\/\/bookafy.com\/wp-content\/uploads\/2023\/02\/bookafy-logo-blue.png 464w, https:\/\/bookafy.com\/wp-content\/uploads\/2023\/02\/bookafy-logo-blue-330x80.png 330w\" sizes=\"(max-width: 464px) 100vw, 464px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-44b214fc elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44b214fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1c7465ab\" data-id=\"1c7465ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9e4735 elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"b9e4735\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-b9e4735\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-334339\"><a href=\"https:\/\/bookafy.com\/pl\/getting-started\/\" class=\"elementor-item\">Getting Started with Bookafy API<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-351585\"><a href=\"https:\/\/bookafy.com\/pl\/elementor-351582\/\" class=\"elementor-item\">Elementor #351582<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-356052\"><a href=\"https:\/\/bookafy.com\/pl\/rockethub\/\" class=\"elementor-item\">RocketHub &#8211; Online Appointment Booking Software<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-360746\"><a href=\"https:\/\/bookafy.com\/pl\/shedul-salon-software\/\" class=\"elementor-item\">Shedul Salon Software Alternative for Salons | Bookafy<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-365523\"><a href=\"https:\/\/bookafy.com\/pl\/hipaa-compliant-scheduling-software\/\" class=\"elementor-item\">HIPAA Compliant Scheduling Software<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-373798\"><a href=\"https:\/\/bookafy.com\/pl\/white-label-booking-for-gohighlevel-agencies\/\" class=\"elementor-item\">White-Label Appointment Booking for GoHighLevel Agencies<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-334347\"><a href=\"https:\/\/bookafy.com\/pl\/single-sign-on-sso\/\" class=\"elementor-item\">Single Sign On &#8211; SSO<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-b9e4735\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-334339\"><a href=\"https:\/\/bookafy.com\/pl\/getting-started\/\" class=\"elementor-item\" tabindex=\"-1\">Getting Started with Bookafy API<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-351585\"><a href=\"https:\/\/bookafy.com\/pl\/elementor-351582\/\" class=\"elementor-item\" tabindex=\"-1\">Elementor #351582<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-356052\"><a href=\"https:\/\/bookafy.com\/pl\/rockethub\/\" class=\"elementor-item\" tabindex=\"-1\">RocketHub &#8211; Online Appointment Booking Software<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-360746\"><a href=\"https:\/\/bookafy.com\/pl\/shedul-salon-software\/\" class=\"elementor-item\" tabindex=\"-1\">Shedul Salon Software Alternative for Salons | Bookafy<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-365523\"><a href=\"https:\/\/bookafy.com\/pl\/hipaa-compliant-scheduling-software\/\" class=\"elementor-item\" tabindex=\"-1\">HIPAA Compliant Scheduling Software<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-373798\"><a href=\"https:\/\/bookafy.com\/pl\/white-label-booking-for-gohighlevel-agencies\/\" class=\"elementor-item\" tabindex=\"-1\">White-Label Appointment Booking for GoHighLevel Agencies<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-334347\"><a href=\"https:\/\/bookafy.com\/pl\/single-sign-on-sso\/\" class=\"elementor-item\" tabindex=\"-1\">Single Sign On &#8211; SSO<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-762630e\" data-id=\"762630e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aa641c5 elementor-widget elementor-widget-text-editor\" data-id=\"1aa641c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"styles--cls2--75613 styles--cls1--379eb styles--headingSize-h1--47930\">Trigger automation with other apps when invitees schedule, cancel, or reschedule events<\/h1><p class=\"styles--cls2--5b16c styles--cls1--f225c\">Our webhook subscription will inform you when invitees book, cancel, or reschedule events. While the process is completely manual, you can use the values within the webhook payload to trigger follow up actions in the internal or custom-built apps you or your team use.<br \/><br \/>If you want to trigger automations without any development work,\u00a0learn more about our integration with Zapier and Make.com, which connects Bookafy to apps you use daily.<\/p><ul class=\"styles--cls2--c1ea4 styles--cls1--5a194\"><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\">When an event is\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">scheduled<\/span>, the\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">invitee.created<\/code><\/span>\u00a0webhook is triggered.<\/p><\/li><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\">When an event is\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">canceled<\/span>, the\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">invitee.canceled<\/code><\/span>\u00a0webhook is triggered.<\/p><\/li><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\">When an event is\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">rescheduled<\/span>, both the\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">invitee.created<\/code><\/span>\u00a0and\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">invitee.canceled<\/code><\/span>\u00a0webhooks are triggered.<\/p><\/li><\/ul><p class=\"styles--cls2--5b16c styles--cls1--f225c\">To learn more about creating a webhook subscription, see\u00a0receive scheduled event data in real time with webhook subscriptions.<\/p><h2 class=\"styles--cls2--75613 styles--cls1--379eb styles--headingSize-h2--5b670\">Webhook payload values<\/h2><p class=\"styles--cls2--5b16c styles--cls1--f225c\">To create your own follow up actions, use the values located within the webhook payload. Some that may be helpful include:<\/p><h3 class=\"styles--cls2--75613 styles--cls1--379eb styles--headingSize-h3--c4f2a\">The event value<\/h3><p class=\"styles--cls2--5b16c styles--cls1--f225c\">The\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">event<\/code><\/span>\u00a0value identifies which payload was triggered as a result of the meeting being scheduled or canceled:<\/p><ul class=\"styles--cls2--c1ea4 styles--cls1--5a194\"><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">event<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\": \"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">invitee.created<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code>\u00a0is triggered when an event is\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">scheduled<\/span><\/p><\/li><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">event<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\": \"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">invitee.canceled<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code>\u00a0is triggered when an event is\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">canceled<\/span><\/p><\/li><\/ul><h3 class=\"styles--cls2--75613 styles--cls1--379eb styles--headingSize-h3--c4f2a\">The status value<\/h3><p class=\"styles--cls2--5b16c styles--cls1--f225c\">The\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">status<\/code><\/span>\u00a0value identifies if the\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">invitee<\/span>\u00a0is attending or not attending the scheduled event<\/p><ul class=\"styles--cls2--c1ea4 styles--cls1--5a194\"><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">status<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\": \"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">active<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code>\u00a0indicates that the invitee will attend the scheduled event<\/p><\/li><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">status<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\": \"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">canceled<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code>\u00a0indicates that the invitee will\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">not<\/span>\u00a0attend the scheduled event<\/p><\/li><\/ul><h3 class=\"styles--cls2--75613 styles--cls1--379eb styles--headingSize-h3--c4f2a\">The canceled value<\/h3><p class=\"styles--cls2--5b16c styles--cls1--f225c\">The\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">canceled<\/code><\/span>\u00a0value identifies if the\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">event<\/span>\u00a0was canceled<\/p><ul class=\"styles--cls2--c1ea4 styles--cls1--5a194\"><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">canceled<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\":\u00a0<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">false<\/code><\/span>\u00a0indicates that the event has\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">not<\/span>\u00a0been canceled<\/p><\/li><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">canceled<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\": true<\/code>\u00a0indicates that the event has been canceled<\/p><ul class=\"styles--cls2--c1ea4 styles--cls1--5a194\"><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\">The\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">canceled_by<\/code><\/span>\u00a0value identifies who, either the Calendly user or invitee, canceled the meeting<\/p><ul class=\"styles--cls2--c1ea4 styles--cls1--5a194\"><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\">The\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">reason<\/code><\/span>\u00a0value (if provided by the canceler) lists the textual response the canceler entered when canceling the event<\/p><\/li><\/ul><\/li><\/ul><\/li><\/ul><h2 class=\"styles--cls2--75613 styles--cls1--379eb styles--headingSize-h2--5b670\">The rescheduled value<\/h2><p class=\"styles--cls2--5b16c styles--cls1--f225c\">The\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">rescheduled<\/code><\/span>\u00a0value identifies if the event has been rescheduled<\/p><ul class=\"styles--cls2--c1ea4 styles--cls1--5a194\"><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">rescheduled<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\":\u00a0<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">true<\/code><\/span>\u00a0indicates the event has been rescheduled<\/p><\/li><li><p class=\"styles--cls2--5b16c styles--cls1--f225c\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\"<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">rescheduled<\/code><\/span><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">\":\u00a0<\/code><span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\"><code class=\"styles--cls2--e18c8 styles--cls1--f5cd2\">false<\/code><\/span>\u00a0indicates the event has\u00a0<span class=\"styles--cls2--f88d7 styles--cls1--fc719 styles--textStyle-bold--0e372\">not<\/span>\u00a0been rescheduled<\/p><\/li><\/ul><h2 class=\"styles--cls2--75613 styles--cls1--379eb styles--headingSize-h2--5b670\">Working with webhooks to analyze data or trigger automation<\/h2><p class=\"styles--cls2--5b16c styles--cls1--f225c\">Put your data to work when you use these guides to receive, understand, and report on Bookafy data when it arrives at an endpoint you specify.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6a06d7 elementor-widget elementor-widget-spacer\" data-id=\"b6a06d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8752213 elementor-section-full_width elementor-section-content-middle elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"8752213\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72b73fce\" data-id=\"72b73fce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1efceb2b elementor-widget elementor-widget-heading\" data-id=\"1efceb2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">\u00a9 Copyright Bookafy 2023<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e9ef88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e9ef88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1be6dd6\" data-id=\"1be6dd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df1047b elementor-widget elementor-widget-image\" data-id=\"df1047b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"330\" height=\"80\" data-src=\"https:\/\/bookafy.com\/wp-content\/uploads\/2023\/04\/bookafy-logo-blue-330x80.png\" class=\"attachment-medium size-medium wp-image-320141 lazyload\" alt=\"appointment booking app\" data-srcset=\"https:\/\/bookafy.com\/wp-content\/uploads\/2023\/04\/bookafy-logo-blue-330x80.png 330w, https:\/\/bookafy.com\/wp-content\/uploads\/2023\/04\/bookafy-logo-blue.png 464w\" data-sizes=\"(max-width: 330px) 100vw, 330px\" title=\"|\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 330px; --smush-placeholder-aspect-ratio: 330\/80;\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ee60e4d\" data-id=\"ee60e4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-319e515 elementor-widget elementor-widget-heading\" data-id=\"319e515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pricing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c816c04 elementor-widget elementor-widget-heading\" data-id=\"c816c04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Resources<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef6ff1c elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"ef6ff1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-ef6ff1c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-316201\"><a href=\"https:\/\/www.youtube.com\/channel\/UC965Z9UHkrF66eYuVBKNURA?view_as=subscriber\" class=\"elementor-item\" rel=\"nofollow noopener\" target=\"_blank\">Video Tutorials<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-316248\"><a href=\"https:\/\/app.bookafy.com\/apidoc\" class=\"elementor-item\">API Docs<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-ef6ff1c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-316201\"><a href=\"https:\/\/www.youtube.com\/channel\/UC965Z9UHkrF66eYuVBKNURA?view_as=subscriber\" class=\"elementor-item\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\">Video Tutorials<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-316248\"><a href=\"https:\/\/app.bookafy.com\/apidoc\" class=\"elementor-item\" tabindex=\"-1\">API Docs<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b2cc6ec\" data-id=\"b2cc6ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b698204 elementor-widget elementor-widget-heading\" data-id=\"b698204\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Product<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c50657a elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"c50657a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-c50657a\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-316405\"><a href=\"https:\/\/www.youtube.com\/channel\/UC965Z9UHkrF66eYuVBKNURA?view_as=subscriber\" class=\"elementor-item\" rel=\"nofollow noopener\" target=\"_blank\">Video Tutorials<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-c50657a\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-316405\"><a href=\"https:\/\/www.youtube.com\/channel\/UC965Z9UHkrF66eYuVBKNURA?view_as=subscriber\" class=\"elementor-item\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\">Video Tutorials<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aee3633 elementor-widget elementor-widget-heading\" data-id=\"aee3633\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partners<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-51c83b6\" data-id=\"51c83b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9661942 elementor-widget elementor-widget-heading\" data-id=\"9661942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solutions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>How It Works Alternatives Get a Price Login Trigger automation with other apps when invitees schedule, cancel, or reschedule events Our webhook subscription will inform you when invitees book, cancel, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":323501,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"categories":[3368,1688],"tags":[3371],"class_list":["post-334309","page","type-page","status-publish","has-post-thumbnail","hentry","category-developer","category-primary-pages","tag-automate-the-process","rishi-post"],"rishi__cb_customizer_meta":"","_links":{"self":[{"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/pages\/334309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/comments?post=334309"}],"version-history":[{"count":1,"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/pages\/334309\/revisions"}],"predecessor-version":[{"id":373444,"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/pages\/334309\/revisions\/373444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/media\/323501"}],"wp:attachment":[{"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/media?parent=334309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/categories?post=334309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bookafy.com\/pl\/wp-json\/wp\/v2\/tags?post=334309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}